{"id":374,"date":"2014-07-04T12:05:25","date_gmt":"2014-07-04T12:05:25","guid":{"rendered":"http:\/\/reflexologiapodal.masajevalencia.es\/?p=374"},"modified":"2022-12-20T20:06:31","modified_gmt":"2022-12-20T20:06:31","slug":"musculos-pelvitrocantereos","status":"publish","type":"post","link":"https:\/\/centremompo.es\/acceder\/musculos-pelvitrocantereos\/","title":{"rendered":"M\u00fasculos pelvitrocantereos"},"content":{"rendered":"<h1>M\u00fasculos pelvitrocantereos<\/h1>\n<blockquote><p>En nuestro trabajo de <strong>Osteopatia<\/strong>, siempre revisamos la pelvis y los m\u00fasculos de la regi\u00f3n gl\u00fatea profunda, conocidos como<\/p>\n<p class=\"query-detail-name\">musculos pelvitrocantereos, vamos all\u00e1!<\/p>\n<\/blockquote>\n<p>Tenemos un grupo muscular formado por seis m\u00fasculos:<\/p>\n<ul>\n<li>Piramidal de la pelvis<\/li>\n<li>G\u00e9mino superio<\/li>\n<li>G\u00e9mino inferior<\/li>\n<li>Obturador interno<\/li>\n<li>Obturador externo<\/li>\n<li>Cuadrado crural<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Piramidal<br \/>\n<\/strong><\/p>\n<div style=\"width: 225px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"http:\/\/www.quiromax.com\/wp-content\/uploads\/2015\/09\/piramidal.jpg\" alt=\"musculo piramidal de la pelvis\" width=\"215\" height=\"207\" \/><p class=\"wp-caption-text\">musculo piramidal de la pelvis<\/p><\/div>\n<p>Su funci\u00f3n es la rotaci\u00f3n externa y abducci\u00f3n del f\u00e9mur cuando la pelvis esta fija. Con la flexi\u00f3n de cadera a 90\u00ba, la rotaci\u00f3n es interna<\/p>\n<p><strong>G\u00e9mino superior<\/strong><\/p>\n<p>Este m\u00fasculo nace en la espina isqui\u00e1tica, justo por debajo de la inserci\u00f3n de algunos fasc\u00edculos del tend\u00f3n del obturador interno. Luego gira hacia la parte superior del tend\u00f3n del obturador interno, por la cara interna de la ep\u00edfisis del f\u00e9mur.<\/p>\n<p>Su contracci\u00f3n estabiliza la articulaci\u00f3n coxofemoral y produce la aducci\u00f3n de la cadera. Tambi\u00e9n causa la rotaci\u00f3n externa del miembro inferior.<\/p>\n<p><strong>G\u00e9mino inferior<\/strong><\/p>\n<p>Nace en la parte superior de la tuberosidad isqui\u00e1tica, justo por debajo de la inserci\u00f3n de algunos fasc\u00edculos del tend\u00f3n del obturador interno. Luego gira hacia la parte inferior del tend\u00f3n del obturador interno, por la cara interna de la ep\u00edfisis del f\u00e9mur, hasta insertarse junto con ese m\u00fasculo.<br \/>\nSu contracci\u00f3n estabiliza la articulaci\u00f3n coxofemoral y produce la aducci\u00f3n de la cadera. Tambi\u00e9n causa la rotaci\u00f3n externa del miembro inferior.[\/tab]<\/p>\n<p><strong><strong>Obturador interno<\/strong><\/strong><\/p>\n<p>Se origina en la superficie intermedia de la membrana obturadora, en el isquion cerca de la membrana, y el borde del pubis. Sale de la cavidad p\u00e9lvica por el agujero ci\u00e1tico menor, se sit\u00faa en parte dentro de la pelvis, y en parte en la regi\u00f3n posterior de la cadera.<br \/>\nSu funci\u00f3n es la de rotador externo de la cadera.<\/p>\n<p><strong><strong><strong>Obturador externo<\/strong><\/strong><\/strong><\/p>\n<p>El obturador externo nace en el margen \u00f3seo lateral del orificio del obturador, de la rama del hueso pubis y de la rama izquierda del isquion. Se inserta detr\u00e1s del cuello del f\u00e9mur, a la altura de la fosita trocant\u00e9rica de ese hueso.<br \/>\nSu acci\u00f3n estabiliza la articulaci\u00f3n coxofemoral y produce la aducci\u00f3n de la cadera. El obturador externo tambi\u00e9n causa la rotaci\u00f3n lateral o hacia afuera del miembro inferior.<\/p>\n<p><strong><strong>Cuadrado crural<\/strong><\/strong><\/p>\n<p>Es aplanado y tiene forma de cuadril\u00e1tero. Se origina en el borde externo de la tuberosidad isqui\u00e1tica, por fuera, baja y se inserta en una l\u00ednea del borde posterior del troc\u00e1nter mayor.<br \/>\nSu acci\u00f3n es la rotaci\u00f3n externa del f\u00e9mur.<\/p>\n<p>En este grupo de m\u00fasculos tenemos rotadores tanto internos como externosy aductores.<br \/>\nLos estiramientos ir\u00e1n enfocados a dichos movimientos, pues vamos a ello!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-8794\" src=\"https:\/\/centremompo.es\/wp-content\/uploads\/2020\/04\/1-1024x574.png\" alt=\"\" width=\"1024\" height=\"574\" srcset=\"https:\/\/centremompo.es\/acceder\/wp-content\/uploads\/2020\/04\/1-1024x574.png 1024w, https:\/\/centremompo.es\/acceder\/wp-content\/uploads\/2020\/04\/1-510x286.png 510w, https:\/\/centremompo.es\/acceder\/wp-content\/uploads\/2020\/04\/1-300x168.png 300w, https:\/\/centremompo.es\/acceder\/wp-content\/uploads\/2020\/04\/1-768x431.png 768w, https:\/\/centremompo.es\/acceder\/wp-content\/uploads\/2020\/04\/1-1080x606.png 1080w, https:\/\/centremompo.es\/acceder\/wp-content\/uploads\/2020\/04\/1.png 1102w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-8817\" src=\"https:\/\/centremompo.es\/wp-content\/uploads\/2014\/07\/Tabla-de-la-musculos-de-la-pelvis.png\" alt=\"\" width=\"609\" height=\"888\" srcset=\"https:\/\/centremompo.es\/acceder\/wp-content\/uploads\/2014\/07\/Tabla-de-la-musculos-de-la-pelvis.png 609w, https:\/\/centremompo.es\/acceder\/wp-content\/uploads\/2014\/07\/Tabla-de-la-musculos-de-la-pelvis-510x744.png 510w, https:\/\/centremompo.es\/acceder\/wp-content\/uploads\/2014\/07\/Tabla-de-la-musculos-de-la-pelvis-206x300.png 206w\" sizes=\"auto, (max-width: 609px) 100vw, 609px\" \/><\/p>\n<h2>Como estirar los m\u00fasculos pelvitrocant\u00e9reos<\/h2>\n<p>Se entienden como m\u00fasculos pelvitrocant\u00e9reos aquellos que van como se puede intuir por el nombre, des de la pelvis al troc\u00e1nter del f\u00e9mur,<\/p>\n<p>Hay que recordar que hay dos troc\u00e1nteres, uno mayor, en la parte m\u00e1s externa y otro menor en la interna.<\/p>\n<h3>Estiramiento de rotadores tumbado<\/h3>\n<p>1. T\u00fambate boca arriba con ambas rodillas flexionadas y los pies apoyados sobre el suelo<br \/>\n2. Pon el tobillo de la pierna que moleste sobre el contrario, lo m\u00e1s cerca de la rodilla posible.<img loading=\"lazy\" decoding=\"async\" class=\" alignright\" src=\"http:\/\/3.bp.blogspot.com\/-rUHCBBzT-os\/UcIlk3ixJvI\/AAAAAAAAAw8\/n50YbbEo6lk\/s1600\/piramidal.jpg\" alt=\"\" width=\"526\" height=\"392\" \/><br \/>\n3. Empuja la rodilla de la pierna afectada hasta sentir un estiramiento suave alrededor de la cadera.<br \/>\n4. Manten el estiramiento de 15 a 30 segundos.<br \/>\n5. Repite de 2 a 4 veces.<br \/>\n6. Repite los pasos del 1 al 5, pero esta vez usa la mano estirar suavemente la rodilla hacia el hombro opuesto.<br \/>\n7. Cambia de piernas y repite los pasos del 1 al 6, aunque solo te moleste una cadera.<\/p>\n<h3>Estiramiento de rotadores internos de la cadera sentado<\/h3>\n<p>1. Si\u00e9ntese en una silla firme.<br \/>\n2. Cruza la pierna que molesta sobre la rodilla, apoyando su pie en la parte superior de la rodilla.<br \/>\n3. Mant\u00e9n la espalda recta e incl\u00ednese lentamente hacia adelante hasta que sientas que tira de la cadera<br \/>\n4. Aguanta la posici\u00f3n entre 15 y 30 segundos.<br \/>\n5. Cambia de piernas y repite los pasos del 1 al 4 del otro lado.<br \/>\n6. Repite de 2 a 4 veces.<\/p>\n<h3>Estiramiento de aductores<\/h3>\n<p>1. Sentado con las piernas abiertas.<br \/>\n2. Incline el troco hacia adelante hasta la tensi\u00f3n muscular en la zona.<br \/>\n3. Mantenga la posici\u00f3n entre 15 y 30 segundos.<br \/>\n4. Repetimos de 2 a 4 veces.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00fasculos pelvitrocantereos En nuestro trabajo de Osteopatia, siempre revisamos la pelvis y los m\u00fasculos de la regi\u00f3n gl\u00fatea profunda, conocidos como musculos pelvitrocantereos, vamos all\u00e1! Tenemos un grupo muscular formado por seis m\u00fasculos: Piramidal de la pelvis G\u00e9mino superio G\u00e9mino inferior Obturador interno Obturador externo Cuadrado crural &nbsp; Piramidal Su funci\u00f3n es la rotaci\u00f3n externa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":368,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[65,1],"tags":[77],"class_list":["post-374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-osteopatia","category-sin-categoria","tag-osteopatia-en-valencia"],"_links":{"self":[{"href":"https:\/\/centremompo.es\/acceder\/wp-json\/wp\/v2\/posts\/374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centremompo.es\/acceder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/centremompo.es\/acceder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/centremompo.es\/acceder\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/centremompo.es\/acceder\/wp-json\/wp\/v2\/comments?post=374"}],"version-history":[{"count":5,"href":"https:\/\/centremompo.es\/acceder\/wp-json\/wp\/v2\/posts\/374\/revisions"}],"predecessor-version":[{"id":8818,"href":"https:\/\/centremompo.es\/acceder\/wp-json\/wp\/v2\/posts\/374\/revisions\/8818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centremompo.es\/acceder\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/centremompo.es\/acceder\/wp-json\/wp\/v2\/media?parent=374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centremompo.es\/acceder\/wp-json\/wp\/v2\/categories?post=374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centremompo.es\/acceder\/wp-json\/wp\/v2\/tags?post=374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}